{"id":51,"count":71,"description":"\u00a1Bienvenido a Emprowear!\r\n\r\nEn nuestra tienda entendemos que la ropa y los accesorios adecuados no solo pueden mejorar tu comodidad durante el ejercicio, sino tambi\u00e9n potenciar tu confianza y motivaci\u00f3n. Por eso, nos esforzamos por ofrecerte una selecci\u00f3n de complementos que no solo sean funcionales, sino tambi\u00e9n estilosos y de alta calidad.\r\n\r\nEstamos constantemente actualizando nuestra colecci\u00f3n para incluir las \u00faltimas tendencias.\r\n\r\nNavega por nuestra tienda en l\u00ednea y descubre una forma de compra f\u00e1cil y conveniente. Con opci\u00f3n de pago seguro y env\u00edo r\u00e1pido.","link":"https:\/\/emprowear.com\/en_us\/product-category\/complementos-outfit\/","name":"Outfit accessories","slug":"complementos-outfit","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":6,"_links":{"self":[{"href":"https:\/\/emprowear.com\/en_us\/wp-json\/wp\/v2\/product_cat\/51","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/emprowear.com\/en_us\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/emprowear.com\/en_us\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/emprowear.com\/en_us\/wp-json\/wp\/v2\/product?product_cat=51"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}